{"id":391,"date":"2019-03-21T00:29:17","date_gmt":"2019-03-21T00:29:17","guid":{"rendered":"https:\/\/mikuszewo.org\/?p=391"},"modified":"2022-02-22T01:35:21","modified_gmt":"2022-02-22T01:35:21","slug":"zew-natury","status":"publish","type":"post","link":"https:\/\/mikuszewo.org\/de\/2019\/03\/zew-natury\/","title":{"rendered":"Natur ruft!"},"content":{"rendered":"<p>Natur ruft! Wir laden Kinder und Jugendliche im Alter von 8-12 Jahren zu einem Treffen voller Natur, interessanter Pflanzen, frischer Luft und Abenteuer ein! Gemeinsam lernen wir, wie eine Tarnung entsteht, bauen H\u00fctten und versuchen die Pflanzenvielfalt zu erkennen. Vielleicht k\u00f6nnen wir das Feuer mit verschiedenen Methoden anz\u00fcnden und mit Musik und Gesang ein Lagerfeuer organisieren?<\/p>\n<p>Nat\u00fcrlich \u00fcben wir die Orientierung im Gel\u00e4nde &#8211; wir erstellen Karten des n\u00e4chstgelegenen Gebiets. Zus\u00e4tzlich werden wir auch gemeinsam die Sterne uns ansehen und versuchen die zu erkennen erkennen. Wir wollen auch Wolken am Himmel entdecken! Sind sie alle gleich? Wie unterscheiden sie sich und wie beeinflussen sie unsere Stimmung und das Wetter? Wir werden diese und andere Fragen stellen und gemeinsam nach Antworten suchen.<\/p>\n<p>Nat\u00fcrlich werden wir auch kreativ! Wir werden n\u00e4hen, mit Ton und Papier basteln! T\u00e4gliche Outdoor-Aktivit\u00e4ten bieten uns auch Bewegungsspiele, Teamspiele und sogar Schnitzeljagd!<\/p>\n<p>Erfahrene polnische und deutsche P\u00e4dagog*innen und Sprachmittler*innen bereiten das Programm vor, k\u00fcmmern sich um die Kinder und sind jederzeit bereit zu einem Gespr\u00e4ch, den Teilnehmenden zu helfen oder wenn n\u00f6tig zu tr\u00f6sten.<br \/>\nDie Unterbringung erfolgt in Mehrpersonenzimmern, zwei Zimmer verf\u00fcgen \u00fcber ein gemeinsames Bad und WC. Die Zuteilung der R\u00e4ume erfolgt zu Beginn des Treffens vor Ort. Nat\u00fcrlich versuchen wir, die W\u00fcnsche von Kindern zu erf\u00fcllen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Natur ruft! Wir laden Kinder und Jugendliche im Alter von 8-12 Jahren zu einem Treffen voller Natur, interessanter Pflanzen, frischer Luft und Abenteuer ein! Gemeinsam lernen wir, wie eine Tarnung entsteht, bauen H\u00fctten und versuchen die Pflanzenvielfalt zu erkennen. Vielleicht k\u00f6nnen wir das Feuer mit verschiedenen Methoden anz\u00fcnden und mit Musik und Gesang ein Lagerfeuer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"hide_page_title":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-391","post","type-post","status-publish","format-standard","hentry","category-archiwum"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"de","enabled_languages":["pl","de","en","ua","ru"],"languages":{"pl":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"ua":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts\/391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/comments?post=391"}],"version-history":[{"count":1,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts\/391\/revisions"}],"predecessor-version":[{"id":392,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts\/391\/revisions\/392"}],"wp:attachment":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/media?parent=391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/categories?post=391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/tags?post=391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}