{"id":152,"date":"2016-02-08T00:51:34","date_gmt":"2016-02-08T00:51:34","guid":{"rendered":"https:\/\/mikuszewo.org\/?p=152"},"modified":"2018-01-02T21:10:36","modified_gmt":"2018-01-02T21:10:36","slug":"dawno-dawno-temu","status":"publish","type":"post","link":"https:\/\/mikuszewo.org\/de\/2016\/02\/dawno-dawno-temu\/","title":{"rendered":"Es war einmal\u2026?"},"content":{"rendered":"<p>Partner: MDSM Mikuszewo<br \/>\nGef\u00f6rdert durch: Deutsch-Polnisches Jugendwerk<br \/>\nZielgruppe: Kinder aus Deutschland und Polen von 8\u201312 Jahren<\/p>\n<p>Es gab einmal in Mikuszewo ein wundersch\u00f6nes Schloss an einem Teich umgebeben von Wiesen und W\u00e4ldern\u2026<\/p>\n<p>Und kaum zu glauben, das Schloss gibt es noch heute! Es l\u00e4dt vor allem Kinder und Jugendliche aus Deutschland und Polen dazu ein, ihren Sommer gemeinsam mit spannenden und lustigen Themen zu verbringen, sich \u00fcber Grenzen hinweg kennen zu lernen, in die Sprache der anderen einzutauchen und mit vielen tollen Erinnerungen wieder nach Hause zu fahren.<br \/>\nIm Mittelpunkt dieser Augustwoche in der Jugendbildungsst\u00e4tte Mikuszewo stehen M\u00e4rchen aus Deutschland und Polen. Mit vielen verschiedenen Techniken basteln wir eine M\u00e4rchenwelt rund um die Geschichten, die wir zu h\u00f6ren bekommen. So entstehen tolle Kost\u00fcme und eine Kulisse f\u00fcr unser eigenes Theaterst\u00fcck, das wir am Ende auff\u00fchren werden.<br \/>\nDabei sind besondere interkulturelle Erfahrungen garantiert \u2013 vielleicht sogar zum ersten Mal ganz ohne Eltern. Erfahrene deutsche und polnische P\u00e4dagogInnen und SprachmittlerInnen gestalten das Programm, betreuen die Kinder und stehen jederzeit als Ansprechpartner zur Verf\u00fcgung.<br \/>\nVeranstaltungsort \/ Unterbringung<\/p>\n<p>Die Jugendbildungsst\u00e4tte Mikuszewo ist langj\u00e4hriger Partner von HochDrei e.V. und befindet sich am Rande eines h\u00fcbschen Dorfes nicht weit von Poznan (Posen). Das Geb\u00e4ude der Begegnungsst\u00e4tte ist ein kleines Schl\u00f6sschen und liegt inmitten einer parkartigen Anlage mit einem kleinen Teich, in dem der Hausmeister stolz seine Karpfen z\u00fcchtet. Rundherum laden Wiesen ein f\u00fcr Sport und Spiel. In der N\u00e4he gibt es ausgedehnte W\u00e4lder. In der direkten Umgebung sind einige Bauernh\u00f6fe angesiedelt, darunter auch ein Reithof.<br \/>\nDie \u00dcbernachtung erfolgt in Mehrbettzimmern. Je zwei Zimmer teilen sich Dusche\/Toilette. Die Zimmerverteilung findet vor Ort statt. Nat\u00fcrlich versuchen wir, auf die W\u00fcnsche der Kinder einzugehen. Mehr Infos zum Haus gibt es auf der Homepage von MDSM MIkuszewo.<\/p>\n<p>Im Teilnahmebeitrag sind keine Fahrtkosten enthalten \u2013 diese betragen von Berlin\/Potsdam aus max. 30\u201340 \u20ac \/ Person. Anreise erfolgt als Gruppe mit BetreuerInnen von Potsdam aus.<\/p>\n<p><a href=\"http:\/\/m.mikuszewo.org\/asset\/2:mikuszewoeswareinmalpdf\" class=\"roll-button button-slider\"><i class=\"fa fa-file-pdf-o\" aria-hidden=\"true\"><\/i>&nbsp;&nbsp;PDF herunterladen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partner: MDSM Mikuszewo Gef\u00f6rdert durch: Deutsch-Polnisches Jugendwerk Zielgruppe: Kinder aus Deutschland und Polen von 8\u201312 Jahren Es gab einmal in Mikuszewo ein wundersch\u00f6nes Schloss an einem Teich umgebeben von Wiesen und W\u00e4ldern\u2026 Und kaum zu glauben, das Schloss gibt es noch heute! Es l\u00e4dt vor allem Kinder und Jugendliche aus Deutschland und Polen dazu ein, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"hide_page_title":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiwum"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"de","enabled_languages":["pl","de","en","ua","ru"],"languages":{"pl":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"ua":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":7,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts\/152\/revisions"}],"predecessor-version":[{"id":243,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/posts\/152\/revisions\/243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/media\/227"}],"wp:attachment":[{"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/media?parent=152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/categories?post=152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mikuszewo.org\/de\/wp-json\/wp\/v2\/tags?post=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}